{"id":696389,"date":"2024-06-13T10:50:08","date_gmt":"2024-06-13T08:50:08","guid":{"rendered":"http:\/\/pith8215.odns.fr\/lot\/appartement-avec-double-balcon-au-coeur-du-village\/"},"modified":"2026-05-11T17:25:21","modified_gmt":"2026-05-11T15:25:21","slug":"appartement-avec-double-balcon-au-coeur-du-village","status":"publish","type":"lot","link":"https:\/\/www.agenceimmoselect.com\/en\/lot\/appartement-avec-double-balcon-au-coeur-du-village\/","title":{"rendered":"Appartement avec double balcon au coeur du village"},"content":{"rendered":"<p>Appartement de 72m\u00b2 en plein c\u0153ur du village, au deuxi\u00e8me \u00e9tage, offrant une atmosph\u00e8re chaleureuse \u00ab\u00a0Comme \u00e0 la maison\u00a0\u00bb \u00e0 quelques pas des pistes. Oubliez votre voiture en r\u00e9servant ce logement de charme et confortable. Les commerces sont \u00e0 proximit\u00e9 imm\u00e9diate et l\u2019acc\u00e8s aux pistes facile par la rue du centre ou du front de neige. Le &#8220;tout \u00e0 pied&#8221; id\u00e9al alliant charme, confort et proximit\u00e9.Class\u00e9 4*. Capacit\u00e9 : 6 personnes.<br \/>\nAdh\u00e9rent Multipass \u00e9t\u00e9 2024<\/p>\n<p>DESCRIPTION:<br \/>\n&#8211; Un hall d&#8217;entr\u00e9e<br \/>\n&#8211; Une chambre double, avec lit de 160cm x 190cm, TV, liseuses et placards int\u00e9gr\u00e9s, acc\u00e8s balcon exposition Nord-Est<br \/>\n&#8211; Une chambre modulable avec deux lits de 90cm x 190cm, ou king size, TV, liseuses et placards int\u00e9gr\u00e9s<br \/>\n&#8211; Une chambre enfant \u00e9quip\u00e9e de 2 lits superpos\u00e9s (80cm x 190cm) avec rangement en tiroirs sous les lits, liseuses<br \/>\n&#8211; Une salle d&#8217;eau avec douche, meuble vasque et s\u00e8che serviettes,<br \/>\n&#8211; Une seconde salle d&#8217;eau avec douche, meuble vasque, s\u00e8che serviettes, machine \u00e0 laver s\u00e9chante<br \/>\n&#8211; 2 WC ind\u00e9pendants<br \/>\n&#8211; Un salon s\u00e9jour \u00e9quip\u00e9 d&#8217;un canap\u00e9, un fauteuil et une m\u00e9ridienne, ouvert sur l\u2019espace repas et la cuisine, donnant acc\u00e8s au balcon expos\u00e9 Nord-Est duquel vous apercevrez le bas des pistes.<br \/>\n&#8211; Une grande cuisine toute \u00e9quip\u00e9e.<\/p>\n<p>EQUIPEMENT : Chauffage collectif, acc\u00e8s wifi, r\u00e9frig\u00e9rateur, freezer, four, micro-ondes, plaques \u00e0 induction, lave-vaisselle int\u00e9gr\u00e9, duo lave-linge s\u00e9chant, bouilloire, grille-pain, machine \u00e0 caf\u00e9 Nespresso, cafeti\u00e8re \u00e0 filtre, mixeur, appareil \u00e0 raclette et fondue, s\u00e8che cheveux .<\/p>\n<p>ANNEXES : 1 casier \u00e0 skis, Local \u00e0 v\u00e9lo collectif (pr\u00e9voir un cadenas).<br \/>\nSERVICES INCLUS L\u2019HIVER :<br \/>\nM\u00e9nage fin de s\u00e9jour, Linge de maison (draps, taies d&#8217;oreiller et housse de couette), Serviettes et tapis de bain. Location de peignoir sur demande, prestations de m\u00e9nage et de blanchisserie interm\u00e9diaires sur demande. Pr\u00e9paration des lits en option (12\u20ac\/lit).<\/p>\n<p>SERVICES INCLUS L\u2019ETE :<br \/>\nM\u00e9nage fin de s\u00e9jour.<br \/>\nTous les autres services sont disponibles en option, sur demande.<\/p>\n<p>CADEAUX de Bienvenue : Kit m\u00e9nage, Kit SDB. Al\u00e8zes jetables \/ Animaux interdits &#8211; Non-fumeurs.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Appartement de 72m\u00b2 en plein c\u0153ur du village, au deuxi\u00e8me \u00e9tage, offrant une atmosph\u00e8re chaleureuse \u00ab\u00a0Comme \u00e0 la maison\u00a0\u00bb \u00e0 quelques pas des pistes. Oubliez votre voiture en r\u00e9servant ce logement de charme et confortable. Les commerces sont \u00e0 proximit\u00e9 imm\u00e9diate et l\u2019acc\u00e8s aux pistes facile par la rue du centre ou du front de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","class_list":["post-696389","lot","type-lot","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Appartement avec double balcon au coeur du village - Agence Immobiliere Les Gets \u2013 Agence Immo Select<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.agenceimmoselect.com\/en\/lot\/appartement-avec-double-balcon-au-coeur-du-village\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Appartement avec double balcon au coeur du village - Agence Immobiliere Les Gets \u2013 Agence Immo Select\" \/>\n<meta property=\"og:description\" content=\"Appartement de 72m\u00b2 en plein c\u0153ur du village, au deuxi\u00e8me \u00e9tage, offrant une atmosph\u00e8re chaleureuse \u00ab\u00a0Comme \u00e0 la maison\u00a0\u00bb \u00e0 quelques pas des pistes. Oubliez votre voiture en r\u00e9servant ce logement de charme et confortable. Les commerces sont \u00e0 proximit\u00e9 imm\u00e9diate et l\u2019acc\u00e8s aux pistes facile par la rue du centre ou du front de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.agenceimmoselect.com\/en\/lot\/appartement-avec-double-balcon-au-coeur-du-village\/\" \/>\n<meta property=\"og:site_name\" content=\"Agence Immobiliere Les Gets \u2013 Agence Immo Select\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T15:25:21+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.agenceimmoselect.com\/en\/lot\/appartement-avec-double-balcon-au-coeur-du-village\/\",\"url\":\"https:\/\/www.agenceimmoselect.com\/en\/lot\/appartement-avec-double-balcon-au-coeur-du-village\/\",\"name\":\"Appartement avec double balcon au coeur du village - Agence Immobiliere Les Gets \u2013 Agence Immo Select\",\"isPartOf\":{\"@id\":\"https:\/\/www.agenceimmoselect.com\/en\/#website\"},\"datePublished\":\"2024-06-13T08:50:08+00:00\",\"dateModified\":\"2026-05-11T15:25:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.agenceimmoselect.com\/en\/lot\/appartement-avec-double-balcon-au-coeur-du-village\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.agenceimmoselect.com\/en\/lot\/appartement-avec-double-balcon-au-coeur-du-village\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.agenceimmoselect.com\/en\/lot\/appartement-avec-double-balcon-au-coeur-du-village\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.agenceimmoselect.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lots\",\"item\":\"https:\/\/www.agenceimmoselect.com\/en\/lot\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Appartement avec double balcon au coeur du village\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.agenceimmoselect.com\/en\/#website\",\"url\":\"https:\/\/www.agenceimmoselect.com\/en\/\",\"name\":\"Agence Immo'Select - Les Gets\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.agenceimmoselect.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.agenceimmoselect.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.agenceimmoselect.com\/en\/#organization\",\"name\":\"Agence Immo'Select - Les Gets\",\"url\":\"https:\/\/www.agenceimmoselect.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.agenceimmoselect.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.agenceimmoselect.com\/wp-content\/uploads\/2022\/06\/IMMO-SELECT_Logo_RVB_Fond-bleu.jpg\",\"contentUrl\":\"https:\/\/www.agenceimmoselect.com\/wp-content\/uploads\/2022\/06\/IMMO-SELECT_Logo_RVB_Fond-bleu.jpg\",\"width\":1783,\"height\":1481,\"caption\":\"Agence Immo'Select - Les Gets\"},\"image\":{\"@id\":\"https:\/\/www.agenceimmoselect.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Appartement avec double balcon au coeur du village - Agence Immobiliere Les Gets \u2013 Agence Immo Select","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.agenceimmoselect.com\/en\/lot\/appartement-avec-double-balcon-au-coeur-du-village\/","og_locale":"en_US","og_type":"article","og_title":"Appartement avec double balcon au coeur du village - Agence Immobiliere Les Gets \u2013 Agence Immo Select","og_description":"Appartement de 72m\u00b2 en plein c\u0153ur du village, au deuxi\u00e8me \u00e9tage, offrant une atmosph\u00e8re chaleureuse \u00ab\u00a0Comme \u00e0 la maison\u00a0\u00bb \u00e0 quelques pas des pistes. Oubliez votre voiture en r\u00e9servant ce logement de charme et confortable. Les commerces sont \u00e0 proximit\u00e9 imm\u00e9diate et l\u2019acc\u00e8s aux pistes facile par la rue du centre ou du front de [&hellip;]","og_url":"https:\/\/www.agenceimmoselect.com\/en\/lot\/appartement-avec-double-balcon-au-coeur-du-village\/","og_site_name":"Agence Immobiliere Les Gets \u2013 Agence Immo Select","article_modified_time":"2026-05-11T15:25:21+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.agenceimmoselect.com\/en\/lot\/appartement-avec-double-balcon-au-coeur-du-village\/","url":"https:\/\/www.agenceimmoselect.com\/en\/lot\/appartement-avec-double-balcon-au-coeur-du-village\/","name":"Appartement avec double balcon au coeur du village - Agence Immobiliere Les Gets \u2013 Agence Immo Select","isPartOf":{"@id":"https:\/\/www.agenceimmoselect.com\/en\/#website"},"datePublished":"2024-06-13T08:50:08+00:00","dateModified":"2026-05-11T15:25:21+00:00","breadcrumb":{"@id":"https:\/\/www.agenceimmoselect.com\/en\/lot\/appartement-avec-double-balcon-au-coeur-du-village\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.agenceimmoselect.com\/en\/lot\/appartement-avec-double-balcon-au-coeur-du-village\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.agenceimmoselect.com\/en\/lot\/appartement-avec-double-balcon-au-coeur-du-village\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.agenceimmoselect.com\/en\/"},{"@type":"ListItem","position":2,"name":"Lots","item":"https:\/\/www.agenceimmoselect.com\/en\/lot\/"},{"@type":"ListItem","position":3,"name":"Appartement avec double balcon au coeur du village"}]},{"@type":"WebSite","@id":"https:\/\/www.agenceimmoselect.com\/en\/#website","url":"https:\/\/www.agenceimmoselect.com\/en\/","name":"Agence Immo'Select - Les Gets","description":"","publisher":{"@id":"https:\/\/www.agenceimmoselect.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.agenceimmoselect.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.agenceimmoselect.com\/en\/#organization","name":"Agence Immo'Select - Les Gets","url":"https:\/\/www.agenceimmoselect.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.agenceimmoselect.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.agenceimmoselect.com\/wp-content\/uploads\/2022\/06\/IMMO-SELECT_Logo_RVB_Fond-bleu.jpg","contentUrl":"https:\/\/www.agenceimmoselect.com\/wp-content\/uploads\/2022\/06\/IMMO-SELECT_Logo_RVB_Fond-bleu.jpg","width":1783,"height":1481,"caption":"Agence Immo'Select - Les Gets"},"image":{"@id":"https:\/\/www.agenceimmoselect.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.agenceimmoselect.com\/en\/wp-json\/wp\/v2\/lot\/696389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.agenceimmoselect.com\/en\/wp-json\/wp\/v2\/lot"}],"about":[{"href":"https:\/\/www.agenceimmoselect.com\/en\/wp-json\/wp\/v2\/types\/lot"}],"author":[{"embeddable":true,"href":"https:\/\/www.agenceimmoselect.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agenceimmoselect.com\/en\/wp-json\/wp\/v2\/comments?post=696389"}],"version-history":[{"count":1,"href":"https:\/\/www.agenceimmoselect.com\/en\/wp-json\/wp\/v2\/lot\/696389\/revisions"}],"predecessor-version":[{"id":704360,"href":"https:\/\/www.agenceimmoselect.com\/en\/wp-json\/wp\/v2\/lot\/696389\/revisions\/704360"}],"wp:attachment":[{"href":"https:\/\/www.agenceimmoselect.com\/en\/wp-json\/wp\/v2\/media?parent=696389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}